{"id":135,"count":1,"description":"","link":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/","name":"Hyatt Regency Coconut Point","slug":"hyatt-regency-coconut-point","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Hyatt Regency Coconut Point Archives - Experience Abroad<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Hyatt Regency Coconut Point Archives - Experience Abroad\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Experience Abroad\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/experienceabroad.com\/wp-content\/uploads\/2021\/03\/joshua-earle-X_roZ7toBJY-unsplash-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/index.php\\\/tag\\\/hyatt-regency-coconut-point\\\/\",\"url\":\"https:\\\/\\\/experienceabroad.com\\\/index.php\\\/tag\\\/hyatt-regency-coconut-point\\\/\",\"name\":\"Hyatt Regency Coconut Point Archives - Experience Abroad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/index.php\\\/tag\\\/hyatt-regency-coconut-point\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/index.php\\\/tag\\\/hyatt-regency-coconut-point\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/experienceabroad.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hyatt Regency Coconut Point\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#website\",\"url\":\"https:\\\/\\\/experienceabroad.com\\\/\",\"name\":\"Experience Abroad\",\"description\":\"Bridging Cultures, Creating Experiences\",\"publisher\":{\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/experienceabroad.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#organization\",\"name\":\"Global Filipino Workforce\",\"alternateName\":\"Philippine Hospitality Partners\",\"url\":\"https:\\\/\\\/experienceabroad.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/experienceabroad.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Experienced-Abroad-Web-Logo.png\",\"contentUrl\":\"https:\\\/\\\/experienceabroad.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Experienced-Abroad-Web-Logo.png\",\"width\":666,\"height\":375,\"caption\":\"Global Filipino Workforce\"},\"image\":{\"@id\":\"https:\\\/\\\/experienceabroad.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExperienceAbroadOfficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/experienceabroadofficial\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/experience-abroad\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hyatt Regency Coconut Point Archives - Experience Abroad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/","og_locale":"en_US","og_type":"article","og_title":"Hyatt Regency Coconut Point Archives - Experience Abroad","og_url":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/","og_site_name":"Experience Abroad","og_image":[{"width":2560,"height":1707,"url":"https:\/\/experienceabroad.com\/wp-content\/uploads\/2021\/03\/joshua-earle-X_roZ7toBJY-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/","url":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/","name":"Hyatt Regency Coconut Point Archives - Experience Abroad","isPartOf":{"@id":"https:\/\/experienceabroad.com\/#website"},"breadcrumb":{"@id":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/experienceabroad.com\/index.php\/tag\/hyatt-regency-coconut-point\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/experienceabroad.com\/"},{"@type":"ListItem","position":2,"name":"Hyatt Regency Coconut Point"}]},{"@type":"WebSite","@id":"https:\/\/experienceabroad.com\/#website","url":"https:\/\/experienceabroad.com\/","name":"Experience Abroad","description":"Bridging Cultures, Creating Experiences","publisher":{"@id":"https:\/\/experienceabroad.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienceabroad.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/experienceabroad.com\/#organization","name":"Global Filipino Workforce","alternateName":"Philippine Hospitality Partners","url":"https:\/\/experienceabroad.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/experienceabroad.com\/#\/schema\/logo\/image\/","url":"https:\/\/experienceabroad.com\/wp-content\/uploads\/2021\/03\/Experienced-Abroad-Web-Logo.png","contentUrl":"https:\/\/experienceabroad.com\/wp-content\/uploads\/2021\/03\/Experienced-Abroad-Web-Logo.png","width":666,"height":375,"caption":"Global Filipino Workforce"},"image":{"@id":"https:\/\/experienceabroad.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExperienceAbroadOfficial\/","https:\/\/www.instagram.com\/experienceabroadofficial\/?hl=en","https:\/\/www.linkedin.com\/company\/experience-abroad"]}]}},"_links":{"self":[{"href":"https:\/\/experienceabroad.com\/index.php\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/experienceabroad.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/experienceabroad.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/experienceabroad.com\/index.php\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}